{"id":1,"name":"admin","url":"https:\/\/depression2.tv","description":"","link":"https:\/\/depression2.tv\/index.php\/author\/admin\/","slug":"admin","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/4dff0f181576b03bce38e4626afdb0a9cbb58798885a21f2f553ba0cd99fba84?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/4dff0f181576b03bce38e4626afdb0a9cbb58798885a21f2f553ba0cd99fba84?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/4dff0f181576b03bce38e4626afdb0a9cbb58798885a21f2f553ba0cd99fba84?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/depression2.tv\/index.php\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depression2.tv\/index.php\/wp-json\/wp\/v2\/users"}]}}